{"id":4233,"date":"2019-10-01T17:52:44","date_gmt":"2019-10-01T20:52:44","guid":{"rendered":"https:\/\/www.usinainfo.com.br\/blog\/?p=4233"},"modified":"2024-11-04T10:18:36","modified_gmt":"2024-11-04T13:18:36","slug":"useless-box-arduino-a-caixa-inutil-com-personalidade","status":"publish","type":"post","link":"https:\/\/www.usinainfo.com.br\/blog\/useless-box-arduino-a-caixa-inutil-com-personalidade\/","title":{"rendered":"Useless Box Arduino \u2013 A Caixa In\u00fatil com Personalidade"},"content":{"rendered":"<p>A Useless Box Arduino, tamb\u00e9m conhecida como Caixa In\u00fatil devido \u00e1 sua tradu\u00e7\u00e3o para o portugu\u00eas, \u00e9 um projeto desenvolvido com o intuito de entreter as pessoas atrav\u00e9s de sua \u201cpersonalidade\u201d e suas rea\u00e7\u00f5es parcialmente espont\u00e2neas \u00e0 est\u00edmulos externos.<\/p>\n<div id=\"attachment_4237\" style=\"width: 711px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/IMG_9650.jpg\" data-rel=\"lightbox-image-0\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4237\" class=\"wp-image-4237\" title=\"\" src=\"https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/IMG_9650-1024x682.jpg\" alt=\"Useless Machine Arduino \u2013 A caixa in\u00fatil em MDF\" width=\"701\" height=\"467\" srcset=\"https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/IMG_9650-1024x682.jpg 1024w, https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/IMG_9650-300x200.jpg 300w, https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/IMG_9650-768x511.jpg 768w, https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/IMG_9650.jpg 1622w\" sizes=\"auto, (max-width: 701px) 100vw, 701px\" \/><\/a><p id=\"caption-attachment-4237\" class=\"wp-caption-text\"><em>Useless Box Arduino \u2013 A caixa in\u00fatil em MDF<\/em><\/p><\/div>\n<p>Normalmente a Useless Box Arduino est\u00e1 associada a projetos makers que tem como objetivo apresentar a eletr\u00f4nica de uma maneira mais divertida, inspirando o gosto e a curiosidade de uma maneira diferenciada.<\/p>\n<p>Bastante utilizada em institui\u00e7\u00f5es de ensino para conquistar adeptos da eletr\u00f4nica, este projeto apresenta um grau de complexidade suficiente para ser utilizado tamb\u00e9m como instrumento de desenvolvimento t\u00e9cnico atrav\u00e9s de exerc\u00edcios de programa\u00e7\u00e3o, por exemplo.<\/p>\n<p>A ideia de funcionamento \u00e9 simples, ao instigar as pessoas \u00e0 liga-la, a Useless Box recusa-se a ficar ligada e de maneira aut\u00f4noma se desliga novamente, cada vez que \u00e9 ativado o interruptor ela apresenta um padr\u00e3o comportamental diferente, mas sempre desligando-se ao final.<\/p>\n<p>&nbsp;<\/p>\n<h2>V\u00eddeo Pr\u00e1tico <strong>Useless Box Arduino<\/strong><\/h2>\n<p><iframe loading=\"lazy\" title=\"USELESS BOX ARDUINO \u2013 A CAIXA IN\u00daTIL COM PERSONALIDADE\" width=\"848\" height=\"477\" src=\"https:\/\/www.youtube.com\/embed\/RWSNgVonUCk?feature=oembed\" style=\"border: none\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Caixa MDF para a Useless Box Arduino<\/strong><\/h2>\n<p>Quem j\u00e1 tentou desenvolver este projeto ou at\u00e9 mesmo j\u00e1 o tenha executado, sabe que a maior dificuldade est\u00e1 no desenvolvimento mec\u00e2nico do mesmo, uma vez que a Useless Box necessita de conex\u00f5es espec\u00edficas e articula\u00e7\u00f5es definidas para cada uma das suas a\u00e7\u00f5es.<\/p>\n<p>Tendo isto em vista, a Usinainfo desenvolveu uma carca\u00e7a em MDF capaz de executar o movimento de at\u00e9 tr\u00eas servos motores, visando um projeto completo e com um exclusivo diferencial, a caixa in\u00fatil desenvolvida pela empresa conta com um terceiro servo al\u00e9m do respons\u00e1vel por erguer a tampa e o respons\u00e1vel por desativar o interruptor.<\/p>\n<p>Este terceiro motor possui a finalidade de proporcionar uma \u201cpegadinha\u201d, vinculado a uma bandeira o mesmo d\u00e1 ind\u00edcios de que a Useless Box se entregou, que desistiu de insistir em desliga-se, podendo ser utilizado como desfecho para suas a\u00e7\u00f5es ou como uma pegadinha, se desligando normalmente ao final de suas a\u00e7\u00f5es.<\/p>\n<div id=\"attachment_4238\" style=\"width: 711px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/IMG_9657.jpg\" data-rel=\"lightbox-image-1\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4238\" class=\"wp-image-4238\" title=\"\" src=\"https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/IMG_9657-1024x682.jpg\" alt=\"Bandeira vinculada ao terceiro servo motor da Useless Machine\" width=\"701\" height=\"467\" srcset=\"https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/IMG_9657-1024x682.jpg 1024w, https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/IMG_9657-300x200.jpg 300w, https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/IMG_9657-768x511.jpg 768w, https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/IMG_9657.jpg 1622w\" sizes=\"auto, (max-width: 701px) 100vw, 701px\" \/><\/a><p id=\"caption-attachment-4238\" class=\"wp-caption-text\"><em>Bandeira vinculada ao terceiro servo motor da Useless Box <\/em><\/p><\/div>\n<p>Outro diferencial desta vers\u00e3o da Useless Box \u00e9 a preocupa\u00e7\u00e3o que se teve com os detalhes que envolviam este projeto, al\u00e9m de terem desenvolvido um equipamento sem necessidade de porcas e parafusos, possibilitando sua montagem atrav\u00e9s de encaixes firmes e seguros, tamb\u00e9m se preocuparam com o design do mesmo.<\/p>\n<p>Um sinal da preocupa\u00e7\u00e3o que se teve com o design de suas pe\u00e7as est\u00e1 na pequena m\u00e3ozinha desenvolvida para fixa\u00e7\u00e3o no sistema de desligamento autom\u00e1tico e que pode ser observada atrav\u00e9s da imagem abaixo:<\/p>\n<div id=\"attachment_4239\" style=\"width: 711px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/IMG_9659.jpg\" data-rel=\"lightbox-image-2\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4239\" class=\"wp-image-4239\" title=\"\" src=\"https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/IMG_9659-1024x682.jpg\" alt=\"Sistema de desarme do interruptor com design exclusivo\" width=\"701\" height=\"467\" srcset=\"https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/IMG_9659-1024x682.jpg 1024w, https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/IMG_9659-300x200.jpg 300w, https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/IMG_9659-768x511.jpg 768w, https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/IMG_9659.jpg 1622w\" sizes=\"auto, (max-width: 701px) 100vw, 701px\" \/><\/a><p id=\"caption-attachment-4239\" class=\"wp-caption-text\"><em>Sistema de desarme do interruptor com design exclusivo<\/em><\/p><\/div>\n<p>Os fatores mencionados acima e todos os demais que envolvem o desenvolvimento da Useless Box Arduino mostram que temos em m\u00e3os um produto que nos possibilitar\u00e1 uma excelente experi\u00eancia de uso, tendo a possibilidade de adquirir a caixa in\u00fatil atrav\u00e9s do site da Usinainfo, s\u00f3 nos basta desenvolver o esquema el\u00e9trico e o c\u00f3digo, ent\u00e3o vamos l\u00e1!<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Produtos Utilizados na Useless Box Arduino<\/strong><\/h2>\n<p>Abaixo seguem todos produtos utilizados no desenvolvimento do projeto, os quais pode ser adquiridos de forma avulsa conforma listagem. Se voc\u00ea quiser, pode adquirir a vers\u00e3o do <a href=\"https:\/\/www.usinainfo.com.br\/kit-robotica-educacional\/useless-box-arduino-caixa-inutil-completa-bs100-5789.html\" target=\"_blank\" rel=\"noopener noreferrer\">Useless Box Arduino Completo<\/a>, o qual j\u00e1 possui todas as pe\u00e7as necess\u00e1rias para montagem.<\/p>\n<p>&#8211; <a href=\"https:\/\/www.usinainfo.com.br\/placas-arduino\/arduino-uno-r3-cabo-usb-3513.html\" target=\"_blank\" rel=\"noopener noreferrer\">Arduino Uno R3 + Cabo USB<\/a>;<\/p>\n<p>&#8211; <a href=\"https:\/\/www.usinainfo.com.br\/kit-robotica-educacional\/case-em-mdf-para-useless-box-caixa-inutil-bs100-5790.html\" target=\"_blank\" rel=\"noopener noreferrer\">Case Useless Box Arduino \u2013 Caixa In\u00fatil<\/a>;<\/p>\n<p>&#8211; <a href=\"https:\/\/www.usinainfo.com.br\/servo-motores\/micro-servo-9g-tower-pro-mg90s-180-com-engrenagens-metalicas-3628.html\" target=\"_blank\" rel=\"noopener noreferrer\">Micro Servo 9g Tower Pro MG90S 180\u00b0 com Engrenagens Met\u00e1licas<\/a>;<\/p>\n<p>&#8211; 2 <a href=\"https:\/\/www.usinainfo.com.br\/servo-motores\/micro-servo-motor-9g-sg90-180-2299.html\" target=\"_blank\" rel=\"noopener noreferrer\">Micro Servo Motor 9g SG90 180\u00b0<\/a>;<\/p>\n<p>&#8211; <a href=\"https:\/\/www.usinainfo.com.br\/protoboard-e-jumpers\/protoboard-170-pontos-para-montagem-de-projetos-2345.html\" target=\"_blank\" rel=\"noopener noreferrer\">Protoboard 170 Pontos para Montagem de Projetos<\/a>;<\/p>\n<p>&#8211; <a href=\"https:\/\/www.usinainfo.com.br\/protoboard-e-jumpers\/jumper-para-protoboard-macho-macho-40-pcs-20cm-2611.html\" target=\"_blank\" rel=\"noopener noreferrer\">Jumper Premium para Protoboard Macho-Macho 20 cm<\/a>;<\/p>\n<p>&#8211; <a href=\"https:\/\/www.usinainfo.com.br\/conectores-e-adaptadores\/chave-alavanca-mts-102-3t-2-posicoes-6a-3704.html\" target=\"_blank\" rel=\"noopener noreferrer\">Chave Alavanca MTS-102 3T 2 Posi\u00e7\u00f5es<\/a>;<\/p>\n<p>&#8211; <a href=\"https:\/\/www.usinainfo.com.br\/conectores-e-adaptadores\/jack-p4-plastico-21x55mm-para-paineis-e-chassis-4749.html\" target=\"_blank\" rel=\"noopener noreferrer\">Jack P4 Pl\u00e1stico (2,1&#215;5,5mm) para Paineis e Chassis<\/a>;<\/p>\n<p>&#8211; <a href=\"https:\/\/www.usinainfo.com.br\/fonte-chaveada-usb-e-p4\/fonte-de-alimentacao-chaveada-6vdc-2a-plug-p4-5376.html\" target=\"_blank\" rel=\"noopener noreferrer\">Fonte de Alimenta\u00e7\u00e3o Chaveada 6VDC 2A;<\/a><\/p>\n<p>&#8211; <a href=\"https:\/\/www.usinainfo.com.br\/parafusos-e-fixadores-396\" target=\"_blank\" rel=\"noopener noreferrer\">Parafusos e Espa\u00e7adores<\/a> (Arduino UNO e Servos).<\/p>\n<p>Optamos pela utiliza\u00e7\u00e3o de um servo motor met\u00e1lico tendo em vista a maior for\u00e7a que o mesmo aplica para a fun\u00e7\u00e3o de desligar o interruptor, agregando maior qualidade ao projeto e evitando que eventualmente o projeto n\u00e3o consiga desenvolver tal fun\u00e7\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Esquema de Liga\u00e7\u00e3o da Caixa In\u00fatil Arduino<\/strong><\/h2>\n<p>Tentaremos replicar o mesmo esquema de liga\u00e7\u00e3o utilizado no desenvolvimento do projeto, com a protoboard e como distribu\u00edmos as liga\u00e7\u00f5es entre motores, Arduino e demais elementos. Segue esquema de liga\u00e7\u00e3o da Useless Box \/ Caixa In\u00fatil:<\/p>\n<div id=\"attachment_6701\" style=\"width: 712px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/caixa-inutil-esquema-de-ligacaoV2.png\" data-rel=\"lightbox-image-3\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-6701\" class=\"wp-image-6701\" title=\"\" src=\"https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/caixa-inutil-esquema-de-ligacaoV2.png\" alt=\"\" width=\"702\" height=\"449\" srcset=\"https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/caixa-inutil-esquema-de-ligacaoV2.png 1688w, https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/caixa-inutil-esquema-de-ligacaoV2-300x192.png 300w, https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/caixa-inutil-esquema-de-ligacaoV2-1024x655.png 1024w, https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/caixa-inutil-esquema-de-ligacaoV2-768x491.png 768w, https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/caixa-inutil-esquema-de-ligacaoV2-1536x983.png 1536w\" sizes=\"auto, (max-width: 702px) 100vw, 702px\" \/><\/a><p id=\"caption-attachment-6701\" class=\"wp-caption-text\"><em>Esquema de liga\u00e7\u00e3o da Useless Box \/ Caixa In\u00fatil<\/em><\/p><\/div>\n<p>Assim como o esquema de liga\u00e7\u00e3o, disponibilizamos tamb\u00e9m o esquema el\u00e9trico do referente projeto, verifique atrav\u00e9s da imagem abaixo:<\/p>\n<div id=\"attachment_6702\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/caixa-inutil-esquema-eletricoV2.png\" data-rel=\"lightbox-image-4\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-6702\" class=\"wp-image-6702\" title=\"\" src=\"https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/caixa-inutil-esquema-eletricoV2.png\" alt=\"\" width=\"700\" height=\"560\" srcset=\"https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/caixa-inutil-esquema-eletricoV2.png 1350w, https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/caixa-inutil-esquema-eletricoV2-300x240.png 300w, https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/caixa-inutil-esquema-eletricoV2-1024x819.png 1024w, https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/caixa-inutil-esquema-eletricoV2-768x614.png 768w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><p id=\"caption-attachment-6702\" class=\"wp-caption-text\"><em>Esquema el\u00e9trico da Useless Box \/ Caixa In\u00fatil<\/em><\/p><\/div>\n<p>Como pudemos ver, o esquema de liga\u00e7\u00e3o \u00e9 bastante simples, o que se torna parcialmente complicado \u00e9 o posicionamento dos produtos dentro da Useless Box Arduino uma vez que o espa\u00e7o para distribui\u00e7\u00e3o \u00e9 relativamente pequeno e a quantia de fios relativamente grande.<\/p>\n<p>Para a conex\u00e3o da fonte de alimenta\u00e7\u00e3o, utilizamos um Jack P4, com fura\u00e7\u00f5es j\u00e1 inclusas no corpo da Caixa In\u00fatil e que possibilita a entrada dos 6V necess\u00e1rios para o funcionamento dos motores, uma vez que a corrente de funcionamento dos mesmos excede os limites da placa Arduino.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>C\u00f3digo de Funcionamento da Useless Box Arduino<\/strong><\/h2>\n<p>O c\u00f3digo de funcionamento da Caixa In\u00fatil \u00e9 parcialmente extenso, por\u00e9m possui cada uma das rea\u00e7\u00f5es da sua \u201cpersonalidade\u201d programadas passo por passo. Um total de sete fun\u00e7\u00f5es foram programadas para expressar as a\u00e7\u00f5es da m\u00e3ozinha que age para desligar o interruptor quando o mesmo \u00e9 ligado.<\/p>\n<p>Iniciamos o c\u00f3digo utilizando a biblioteca Servo.h, por\u00e9m a mesmo n\u00e3o possibilitava um ajuste t\u00e3o preciso do movimento e acabava trepidando bastante a tampa em rela\u00e7\u00e3o ao dispositivo que \u00e0 levantava. Tendo isto em vista, a biblioteca Servo.h foi substitu\u00edda pela biblioteca VarSpeedServo.h, o que possibilitou um controle de velocidade e melhorou o funcionamento da Useless Box Arduino.<\/p>\n<p>Biblioteca VarSpeedServo.h: <a href=\"https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/VarSpeedServo.zip\">DOWNLOAD AQUI<\/a>.<\/p>\n<p>Segue c\u00f3digo completo de funcionamento da Caixa In\u00fatil:<\/p>\n<pre class=\"lang:c# decode:true\">\/\/ C\u00f3digo de funcioanmento da Useless Box Arduino\r\n\/\/ C\u00f3digo com 7 rea\u00e7\u00f5es diferentes de desligar\r\n\r\n#include &lt;VarSpeedServo.h&gt;\u00a0\u00a0\u00a0 \/\/ Inclui a biblioteca VarSpeedServo\r\n\r\nVarSpeedServo mao;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \/\/ Declara a vari\u00e1vel mao\r\nVarSpeedServo tampa;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \/\/ Declara a vari\u00e1vel tampa\r\nVarSpeedServo bandeira;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \/\/ Declara a vari\u00e1vel abndeira\r\n\r\nint alavanca = 8 ;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \/\/ Determina o pino 8 como alavanca\r\nint reacao = 1;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \/\/ Declara o valor da vari\u00e1vel reacao\r\nint angulo = 0;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \/\/ Declara o angulo padr\u00e3o de a\u00e7\u00e3o\r\n\r\nvoid setup() {\r\n\u00a0 pinMode(alavanca, INPUT);\u00a0 \/\/ Define o pino da alavanca como entrada\r\n\u00a0 mao.attach(3);\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \/\/ Define o pino 3 (PWM) como mao\r\n\u00a0 tampa.attach(5);\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \/\/ Define o pino 5 (PWM) como tampa\r\n\u00a0 bandeira.attach(6);\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \/\/ Define o pino 6 (PWM) como bandeira\r\n\r\n\u00a0 mao.write(180);\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \/\/ \u00c2ngulo inicial da mao em 180\r\n\u00a0 tampa.write(90);\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \/\/ \u00c2ngulo inicial da tampa em 90\r\n\u00a0 bandeira.write(180);\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \/\/ \u00c2ngulo inicial da bandeira em 180\r\n}\r\n\r\nvoid loop() {\r\n\r\n\u00a0 \/\/ Declara o n\u00famero de rea\u00e7\u00f5es da m\u00e1quina e as nomeia\r\n\u00a0 if (digitalRead(alavanca) == LOW)\u00a0 {\r\n\u00a0\u00a0\u00a0 if (reacao &gt; 7) {\r\n\u00a0\u00a0\u00a0\u00a0\u00a0 reacao = 1;\r\n\u00a0\u00a0\u00a0 }\r\n\u00a0\u00a0\u00a0 if (reacao == 1) {\r\n\u00a0\u00a0\u00a0\u00a0\u00a0 reacao1();\r\n\u00a0\u00a0\u00a0 }\r\n\u00a0\u00a0\u00a0 else if (reacao == 2) {\r\n\u00a0\u00a0\u00a0\u00a0\u00a0 reacao2();\r\n\u00a0\u00a0\u00a0 }\r\n\u00a0\u00a0\u00a0 else if (reacao == 3) {\r\n\u00a0\u00a0\u00a0\u00a0\u00a0 reacao3();\r\n\u00a0\u00a0\u00a0 }\r\n\u00a0\u00a0\u00a0 else if (reacao == 4) {\r\n\u00a0\u00a0\u00a0\u00a0\u00a0 reacao4();\r\n\u00a0\u00a0\u00a0 }\r\n\u00a0\u00a0\u00a0 else if (reacao == 5) {\r\n\u00a0\u00a0\u00a0\u00a0\u00a0 reacao5();\r\n\u00a0\u00a0\u00a0 }\r\n\u00a0\u00a0\u00a0 else if (reacao == 6) {\r\n\u00a0\u00a0\u00a0\u00a0\u00a0 reacao6();\r\n\u00a0\u00a0\u00a0 }\r\n\u00a0\u00a0\u00a0 else if (reacao == 7) {\r\n\u00a0\u00a0\u00a0\u00a0\u00a0 reacao7();\r\n\u00a0\u00a0\u00a0 }\r\n\u00a0\u00a0\u00a0 reacao += 1;\r\n\u00a0 }\r\n}\r\n\r\n\/\/ Configura as a\u00e7\u00f5es da rea\u00e7\u00e3o 1\r\nvoid reacao1() {\r\n\u00a0 tampa.write(45, 50, true);\r\n\u00a0 delay(1000);\r\n\u00a0 mao.write(80);\r\n\u00a0 delay(500);\r\n\u00a0 mao.write(180);\r\n\u00a0 delay(1000);\r\n\u00a0 tampa.write(90, 50, true);\r\n\u00a0 delay(1000);\r\n}\r\n\r\n\/\/ Configura as a\u00e7\u00f5es da rea\u00e7\u00e3o 2\r\nvoid reacao2() {\r\n\u00a0 tampa.write(45, 30, true);\r\n\u00a0 delay(1000);\r\n\u00a0 mao.write(80);\r\n\u00a0 delay(250);\r\n\u00a0 mao.write(180);\r\n\u00a0 delay(100);\r\n\u00a0 tampa.write(90);\r\n}\r\n\r\n\/\/ Configura as a\u00e7\u00f5es da rea\u00e7\u00e3o 3\r\nvoid reacao3() {\r\n\u00a0 tampa.write(30, 60, true);\r\n\u00a0 mao.write(80);\r\n\u00a0 delay(250);\r\n\u00a0 mao.write(180);\r\n\u00a0 delay(100);\r\n\u00a0 tampa.write(90);\r\n}\r\n\r\n\/\/ Configura as a\u00e7\u00f5es da rea\u00e7\u00e3o 4\r\nvoid reacao4() {\r\n\u00a0 delay(250);\r\n\u00a0 tampa.write(20, 60, true);\r\n\u00a0 delay(100);\r\n\u00a0 mao.write(80);\r\n\u00a0 delay(2500);\r\n\u00a0 for (angulo = 80; angulo &gt; 180; angulo -= 1)\u00a0 {\r\n\u00a0\u00a0\u00a0 mao.write(angulo);\r\n\u00a0\u00a0\u00a0 delay(50);\r\n\u00a0 }\r\n\u00a0 mao.write(180, 30, true);\r\n\u00a0 delay(500);\r\n\u00a0 tampa.write(90);\r\n}\r\n\r\n\/\/ Configura as a\u00e7\u00f5es da rea\u00e7\u00e3o 5\r\nvoid reacao5() {\r\n\u00a0 tampa.write(50, 60, true);\r\n\u00a0 delay(500);\r\n\u00a0 tampa.write(90, 80, true);\r\n\u00a0 delay(1000);\r\n\u00a0 tampa.write(50, 60, true);\r\n\u00a0 delay(500);\r\n\u00a0 tampa.write(90, 80, true);\r\n\u00a0 delay(1000);\r\n\u00a0 tampa.write(50, 60, true);\r\n\u00a0 delay(500);\r\n\u00a0 tampa.write(90, 80, true);\r\n\u00a0 delay(2500);\r\n\u00a0 tampa.write(30, 60, true);\r\n\u00a0 delay(100);\r\n\u00a0 mao.write(80);\r\n\u00a0 delay(250);\r\n\u00a0 mao.write(180);\r\n\u00a0 delay(100);\r\n\u00a0 tampa.write(90);\r\n}\r\n\r\n\/\/ Configura as a\u00e7\u00f5es da rea\u00e7\u00e3o 6\r\nvoid reacao6() {\r\n\u00a0 tampa.write(25, 60, true);\r\n\u00a0 delay(100);\r\n\u00a0 mao.write(110);\r\n\u00a0 delay(250);\r\n\u00a0 mao.write(180);\r\n\u00a0 delay(100);\r\n\u00a0 tampa.write(90, 80, true);\r\n\u00a0 delay(250);\r\n\u00a0 tampa.write(25, 60, true);\r\n\u00a0 delay(100);\r\n\u00a0 mao.write(110);\r\n\u00a0 delay(250);\r\n\u00a0 mao.write(180, 30, true);\r\n\u00a0 delay(100);\r\n\u00a0 tampa.write(90, 80, true);\r\n\u00a0 delay(250);\r\n\u00a0 tampa.write(25, 60, true);\r\n\u00a0 delay(100);\r\n\u00a0 mao.write(110, 30, true);\r\n\u00a0 delay(250);\r\n\u00a0 mao.write(180);\r\n\u00a0 delay(100);\r\n\u00a0 tampa.write(90, 80, true);\r\n\u00a0 delay(250);\r\n\u00a0 tampa.write(25, 60, true);\r\n\u00a0 delay(100);\r\n\u00a0 mao.write(80);\r\n\u00a0 delay(250);\r\n\u00a0 mao.write(180);\r\n\u00a0 delay(100);\r\n\u00a0 tampa.write(90);\r\n}\r\n\r\n\/\/ Configura as a\u00e7\u00f5es da rea\u00e7\u00e3o 7\r\nvoid reacao7() {\r\n\u00a0 tampa.write(20, 60, true);\r\n\u00a0 delay(500);\r\n\u00a0 bandeira.write(0, 30, true);\r\n\u00a0 bandeira.write(45, 30, true);\r\n\u00a0 bandeira.write(0, 30, true);\r\n\u00a0 bandeira.write(30, 30, true);\r\n\u00a0 bandeira.write(0, 30, true);\r\n\u00a0 bandeira.write(45, 30, true);\r\n\u00a0 bandeira.write(0, 30, true);\r\n\u00a0 bandeira.write(30, 30, true);\r\n\u00a0 bandeira.write(0, 30, true);\r\n\u00a0 bandeira.write(45, 30, true);\r\n\u00a0 bandeira.write(0, 30, true);\r\n\u00a0 delay(2000);\r\n\u00a0 bandeira.write(180);\r\n\u00a0 delay(2000);\r\n\u00a0 tampa.write(35, 30, true);\r\n\u00a0 mao.write(80);\r\n\u00a0 delay(250);\r\n\u00a0 mao.write(180);\r\n\u00a0 delay(500);\r\n\u00a0 tampa.write(90);\r\n}<\/pre>\n<p>Dentre os elementos utilizados no c\u00f3digo, um dos que mais pode causar d\u00favidas \u00e9 o que segue:<\/p>\n<pre class=\"lang:c# decode:true \">bandeira.write(45, 30, true);<\/pre>\n<p>O seu funcionamento \u00e9 bastante simples, baseado na biblioteca VarSpeedServo.h esta fun\u00e7\u00e3o determina que o servo nomeado bandeira execute um movimento at\u00e9 o \u00e2ngulo de 45\u00ba com uma velocidade de 30 e s\u00f3 execute a pr\u00f3xima fun\u00e7\u00e3o quando tiver chegado ao seu objetivo, ou seja:<\/p>\n<pre class=\"lang:c# decode:true \">servo.write(\u00e2ngulo, velocidade, true);<\/pre>\n<p>As principais fun\u00e7\u00f5es do c\u00f3digo est\u00e3o todas explicadas com as respectivas observa\u00e7\u00f5es e coment\u00e1rios necess\u00e1rios para sua compreens\u00e3o, por\u00e9m vale ressaltar um item bastante importante quanto ao c\u00f3digo, o ato de copi\u00e1-lo e col\u00e1-lo n\u00e3o significa que ir\u00e1 funcionar em seu projeto sem nenhum tipo de adapta\u00e7\u00e3o \/ altera\u00e7\u00e3o, isto ocorre uma vez que os servos podem ser instalados de maneiras diferentes, o que iria alterar os \u00e2ngulos de funcionamento do projeto.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Calibra\u00e7\u00e3o dos Servos Motores da Useless Box Arduino<\/strong><\/h2>\n<p>O principal fator de funcionamento do projeto est\u00e1 no trabalho executado pelos servos motores, afinal de contas, eles executam todo o trabalho que a Useless Box desenvolve. Tendo isto em vista, \u00e9 necess\u00e1ria a calibra\u00e7\u00e3o de posi\u00e7\u00e3o dos mesmos de acordo com o intervalo de movimento poss\u00edvel para execu\u00e7\u00e3o de todas as suas fun\u00e7\u00f5es.<\/p>\n<p>Para entendermos melhor, vamos utilizar o servo motor conectado a m\u00e3o que desliga o interruptor como exemplo, veja abaixo o c\u00f3digo utilizado para deslocamento do bra\u00e7o de sua posi\u00e7\u00e3o final at\u00e9 sua posi\u00e7\u00e3o inicial assim como uma imagem que ilustra este procedimento:<\/p>\n<pre class=\"lang:c# decode:true\">  mao.write(80);\r\n\u00a0 delay(500);\r\n\u00a0 mao.write(180);\r\n\u00a0 delay(1000);<\/pre>\n<div id=\"attachment_4236\" style=\"width: 828px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/comparacao-angulo-mao-useless-machine.jpg\" data-rel=\"lightbox-image-5\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4236\" class=\"wp-image-4236 \" title=\"\" src=\"https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/comparacao-angulo-mao-useless-machine-1024x341.jpg\" alt=\"Representa\u00e7\u00e3o dos \u00e2ngulos de trabalho da Useless Box Arduino\" width=\"818\" height=\"272\" srcset=\"https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/comparacao-angulo-mao-useless-machine-1024x341.jpg 1024w, https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/comparacao-angulo-mao-useless-machine-300x100.jpg 300w, https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/comparacao-angulo-mao-useless-machine-768x256.jpg 768w, https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/comparacao-angulo-mao-useless-machine.jpg 1544w\" sizes=\"auto, (max-width: 818px) 100vw, 818px\" \/><\/a><p id=\"caption-attachment-4236\" class=\"wp-caption-text\"><em>Representa\u00e7\u00e3o dos \u00e2ngulos de trabalho da Useless Box Arduino<\/em><\/p><\/div>\n<p>Para realizar esta calibra\u00e7\u00e3o, foi utilizado o c\u00f3digo de funcionamento do servo motor dispon\u00edvel no Blog da Usinainfo, com ele \u00e9 delimitado o \u00e2ngulo de funcionamento do servo e atrav\u00e9s de um m\u00e9todo de tentativa e erro vamos ajustando o \u00e2ngulo padr\u00e3o de nossos equipamentos.<\/p>\n<p>Normalmente, quando trabalhamos com os servos SG90 o \u00e2ngulo inicial ser\u00e1 aproximadamente 180\u00ba ou aproximadamente 0\u00ba, por\u00e9m apenas testando o servo quando j\u00e1 instalado na Useless Box Arduino para termos ideia destes valores.<\/p>\n<p>O principal cuidado que precisamos ter \u00e9 quanto ao \u00e2ngulo final que deve ser o menor poss\u00edvel, evitando press\u00f5es excessivas com a alavanca, por exemplo, para que n\u00e3o ocorra danos ao servo e seja necess\u00e1ria poss\u00edvel troca posteriormente.<\/p>\n<p>O artigo utilizado como base para o teste dos servos \u00e9 o que segue:<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"a8bGFgMDpJ\"><p><a href=\"https:\/\/www.usinainfo.com.br\/blog\/controle-de-posicao-servo-motor-com-arduino\/\">Controle de Posi\u00e7\u00e3o Servo Motor com Arduino<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;Controle de Posi\u00e7\u00e3o Servo Motor com Arduino&#8221; &#8212; Blog Usinainfo\" src=\"https:\/\/www.usinainfo.com.br\/blog\/controle-de-posicao-servo-motor-com-arduino\/embed\/#?secret=OapPVtoMI8#?secret=a8bGFgMDpJ\" data-secret=\"a8bGFgMDpJ\" width=\"600\" height=\"338\" style=\"border: none\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Conclus\u00e3o<\/strong><\/h2>\n<p>Inicialmente, o projeto parece ser extremamente f\u00e1cil, por\u00e9m o desenvolvimento geral dele mostrou-se um pouco desafiador, uma vez que existe a necessidade de calibra\u00e7\u00e3o, vale lembrar que se os \u00e2ngulos iniciais e finais forem alterados, devem-se alterar todos os demais \u00e2ngulos do devido servo no c\u00f3digo para movimentos compat\u00edveis.<\/p>\n<p>Os demais detalhes de funcionamento s\u00e3o extremamente condicentes com a vis\u00e3o inicial de surpresa e entretenimento, uma vez que para quem tem o primeiro contato com a Useless Box Arduino se surpreende com a rea\u00e7\u00e3o da mesma.<\/p>\n<p>Em um contexto geral, como o pr\u00f3prio nome j\u00e1 representa, a Caixa In\u00fatil n\u00e3o possui grandes funcionalidades, por\u00e9m \u00e9 bastante \u00fatil para quem deseja aprimorar os seus conhecimentos e desafiar-se no mundo da programa\u00e7\u00e3o e desenvolvimento de projetos.<\/p>\n<p>N\u00e3o deixe de comentar sobre o que achou e quais as experi\u00eancias que teve ao desenvolver a sua Useless Box Arduino, compartilhe suas dificuldades e ajude os demais que tamb\u00e9m desejam realizar o seu projeto a encontrar o \u00eaxito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Useless Box Arduino, tamb\u00e9m conhecida como Caixa In\u00fatil devido \u00e1 sua tradu\u00e7\u00e3o para o portugu\u00eas, \u00e9 um projeto desenvolvido com o intuito de entreter as pessoas atrav\u00e9s de sua \u201cpersonalidade\u201d e suas rea\u00e7\u00f5es parcialmente espont\u00e2neas \u00e0 est\u00edmulos externos. Normalmente a Useless Box Arduino est\u00e1 associada a projetos makers que tem como objetivo apresentar a eletr\u00f4nica de uma maneira mais divertida, inspirando o gosto e a curiosidade de uma maneira diferenciada. Bastante utilizada em institui\u00e7\u00f5es de ensino para conquistar adeptos da eletr\u00f4nica, este projeto apresenta um grau de complexidade suficiente para ser utilizado tamb\u00e9m como instrumento de desenvolvimento t\u00e9cnico atrav\u00e9s de exerc\u00edcios de programa\u00e7\u00e3o, por exemplo. A ideia de funcionamento \u00e9 simples, ao instigar as pessoas \u00e0 liga-la, a Useless [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":4239,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,1],"tags":[],"class_list":["post-4233","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arduino","category-projetos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Useless Box Arduino \u2013 A Caixa In\u00fatil com Personalidade - Blog Usinainfo<\/title>\n<meta name=\"description\" content=\"Projeto da Useless Box Arduino Caixa In\u00fatil tem no Blog Usinainfo. Tutorial Completo com Esquema El\u00e9trico e C\u00f3digo de Programa\u00e7\u00e3o. Confira Agora!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.usinainfo.com.br\/blog\/useless-box-arduino-a-caixa-inutil-com-personalidade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Useless Box Arduino \u2013 A Caixa In\u00fatil com Personalidade - Blog Usinainfo\" \/>\n<meta property=\"og:description\" content=\"Projeto da Useless Box Arduino Caixa In\u00fatil tem no Blog Usinainfo. Tutorial Completo com Esquema El\u00e9trico e C\u00f3digo de Programa\u00e7\u00e3o. Confira Agora!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.usinainfo.com.br\/blog\/useless-box-arduino-a-caixa-inutil-com-personalidade\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Usinainfo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/pt-br.facebook.com\/faceusinainfo\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-01T20:52:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-04T13:18:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/IMG_9659.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1622\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Matheus Gebert Straub\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matheus Gebert Straub\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Useless Box Arduino \u2013 A Caixa In\u00fatil com Personalidade - Blog Usinainfo","description":"Projeto da Useless Box Arduino Caixa In\u00fatil tem no Blog Usinainfo. Tutorial Completo com Esquema El\u00e9trico e C\u00f3digo de Programa\u00e7\u00e3o. Confira Agora!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.usinainfo.com.br\/blog\/useless-box-arduino-a-caixa-inutil-com-personalidade\/","og_locale":"pt_BR","og_type":"article","og_title":"Useless Box Arduino \u2013 A Caixa In\u00fatil com Personalidade - Blog Usinainfo","og_description":"Projeto da Useless Box Arduino Caixa In\u00fatil tem no Blog Usinainfo. Tutorial Completo com Esquema El\u00e9trico e C\u00f3digo de Programa\u00e7\u00e3o. Confira Agora!","og_url":"https:\/\/www.usinainfo.com.br\/blog\/useless-box-arduino-a-caixa-inutil-com-personalidade\/","og_site_name":"Blog Usinainfo","article_publisher":"https:\/\/pt-br.facebook.com\/faceusinainfo\/","article_published_time":"2019-10-01T20:52:44+00:00","article_modified_time":"2024-11-04T13:18:36+00:00","og_image":[{"width":1622,"height":1080,"url":"https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/IMG_9659.jpg","type":"image\/jpeg"}],"author":"Matheus Gebert Straub","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Matheus Gebert Straub","Est. tempo de leitura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.usinainfo.com.br\/blog\/useless-box-arduino-a-caixa-inutil-com-personalidade\/#article","isPartOf":{"@id":"https:\/\/www.usinainfo.com.br\/blog\/useless-box-arduino-a-caixa-inutil-com-personalidade\/"},"author":{"name":"Matheus Gebert Straub","@id":"https:\/\/www.usinainfo.com.br\/blog\/#\/schema\/person\/22905ec7c8d47a176b7c2320b66cd075"},"headline":"Useless Box Arduino \u2013 A Caixa In\u00fatil com Personalidade","datePublished":"2019-10-01T20:52:44+00:00","dateModified":"2024-11-04T13:18:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.usinainfo.com.br\/blog\/useless-box-arduino-a-caixa-inutil-com-personalidade\/"},"wordCount":1693,"commentCount":11,"image":{"@id":"https:\/\/www.usinainfo.com.br\/blog\/useless-box-arduino-a-caixa-inutil-com-personalidade\/#primaryimage"},"thumbnailUrl":"https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/IMG_9659.jpg","articleSection":["Arduino","Projetos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.usinainfo.com.br\/blog\/useless-box-arduino-a-caixa-inutil-com-personalidade\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.usinainfo.com.br\/blog\/useless-box-arduino-a-caixa-inutil-com-personalidade\/","url":"https:\/\/www.usinainfo.com.br\/blog\/useless-box-arduino-a-caixa-inutil-com-personalidade\/","name":"Useless Box Arduino \u2013 A Caixa In\u00fatil com Personalidade - Blog Usinainfo","isPartOf":{"@id":"https:\/\/www.usinainfo.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.usinainfo.com.br\/blog\/useless-box-arduino-a-caixa-inutil-com-personalidade\/#primaryimage"},"image":{"@id":"https:\/\/www.usinainfo.com.br\/blog\/useless-box-arduino-a-caixa-inutil-com-personalidade\/#primaryimage"},"thumbnailUrl":"https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/IMG_9659.jpg","datePublished":"2019-10-01T20:52:44+00:00","dateModified":"2024-11-04T13:18:36+00:00","author":{"@id":"https:\/\/www.usinainfo.com.br\/blog\/#\/schema\/person\/22905ec7c8d47a176b7c2320b66cd075"},"description":"Projeto da Useless Box Arduino Caixa In\u00fatil tem no Blog Usinainfo. Tutorial Completo com Esquema El\u00e9trico e C\u00f3digo de Programa\u00e7\u00e3o. Confira Agora!","breadcrumb":{"@id":"https:\/\/www.usinainfo.com.br\/blog\/useless-box-arduino-a-caixa-inutil-com-personalidade\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.usinainfo.com.br\/blog\/useless-box-arduino-a-caixa-inutil-com-personalidade\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.usinainfo.com.br\/blog\/useless-box-arduino-a-caixa-inutil-com-personalidade\/#primaryimage","url":"https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/IMG_9659.jpg","contentUrl":"https:\/\/www.usinainfo.com.br\/blog\/wp-content\/uploads\/2019\/10\/IMG_9659.jpg","width":1622,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.usinainfo.com.br\/blog\/useless-box-arduino-a-caixa-inutil-com-personalidade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.usinainfo.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Useless Box Arduino \u2013 A Caixa In\u00fatil com Personalidade"}]},{"@type":"WebSite","@id":"https:\/\/www.usinainfo.com.br\/blog\/#website","url":"https:\/\/www.usinainfo.com.br\/blog\/","name":"Blog Usinainfo","description":"Usinainfo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.usinainfo.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.usinainfo.com.br\/blog\/#\/schema\/person\/22905ec7c8d47a176b7c2320b66cd075","name":"Matheus Gebert Straub","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/04cea122706965cd2cb1d4f867fae66443684a4df025a4ba047491d6fad7c05e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/04cea122706965cd2cb1d4f867fae66443684a4df025a4ba047491d6fad7c05e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/04cea122706965cd2cb1d4f867fae66443684a4df025a4ba047491d6fad7c05e?s=96&d=mm&r=g","caption":"Matheus Gebert Straub"},"description":"Mec\u00e2nico de Manuten\u00e7\u00e3o com Experi\u00eancia em Sistemas Embarcados, Automa\u00e7\u00e3o e Desenvolvimento de Projetos; Graduado nos Cursos de Matem\u00e1tica - URI e F\u00edsica - UFFS.","url":"https:\/\/www.usinainfo.com.br\/blog\/author\/matheus\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.usinainfo.com.br\/blog\/wp-json\/wp\/v2\/posts\/4233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.usinainfo.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.usinainfo.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.usinainfo.com.br\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.usinainfo.com.br\/blog\/wp-json\/wp\/v2\/comments?post=4233"}],"version-history":[{"count":12,"href":"https:\/\/www.usinainfo.com.br\/blog\/wp-json\/wp\/v2\/posts\/4233\/revisions"}],"predecessor-version":[{"id":6703,"href":"https:\/\/www.usinainfo.com.br\/blog\/wp-json\/wp\/v2\/posts\/4233\/revisions\/6703"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.usinainfo.com.br\/blog\/wp-json\/wp\/v2\/media\/4239"}],"wp:attachment":[{"href":"https:\/\/www.usinainfo.com.br\/blog\/wp-json\/wp\/v2\/media?parent=4233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.usinainfo.com.br\/blog\/wp-json\/wp\/v2\/categories?post=4233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.usinainfo.com.br\/blog\/wp-json\/wp\/v2\/tags?post=4233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}